{"id":12430,"date":"2024-10-14T11:48:40","date_gmt":"2024-10-14T10:48:40","guid":{"rendered":"https:\/\/radioalma.eu\/bruselas\/?p=12430"},"modified":"2024-10-14T12:09:41","modified_gmt":"2024-10-14T11:09:41","slug":"una-buena-obra-lleva-al-escenario-una-version-comica-de-romeo-y-julieta","status":"publish","type":"post","link":"https:\/\/radioalma.eu\/bruselas\/2024\/10\/14\/una-buena-obra-lleva-al-escenario-una-version-comica-de-romeo-y-julieta\/","title":{"rendered":"&#8216;Una Buena Obra&#8217; lleva al escenario una versi\u00f3n c\u00f3mica de Romeo y Julieta"},"content":{"rendered":"\n<p><strong>El \u00faltimo programa de Bruselas con \u00d1 se convirti\u00f3 en un para\u00edso cultural<\/strong> que llev\u00f3 hasta nuestros oyentes desde un festival de m\u00fasica belga y valenciana hasta la<strong> cl\u00e1sica joya de teatro que la compa\u00f1\u00eda &#8216;Una Buena Obra&#8217;<\/strong> ha preparado.\u00a0 Se trata de <span style=\"font-weight: 400\"><strong>Romeo y Julieta<\/strong>, la historia de amor eterno por antonomasia de la que todos hemos escuchado hablar alguna vez. A\u00fan as\u00ed, daremos una pincelada de repaso para todos aquellos que no recuerden muy bien la trama.<\/span><\/p>\n<p>Nos situamos en la Italia de principios del siglo XVI, concretamente en Verona, donde dos j\u00f3venes amantes procedentes de familias opuestas, los Capuleto y los Montesco, son v\u00edctimas de una situaci\u00f3n de odio y violencia que no quieren ni pueden remediar. Un d\u00eda en el que se respiraba la tranquilidad, Romeo, reci\u00e9n casado en secreto con su amada Julieta, junto sus primos Benvolio y Mercucio, se enzarza en una pelea con Teobaldo, el primo de su esposa, en la que finalmente este acaba asesinado a manos de Romeo. A partir de ah\u00ed se desata la tragedia y los acontecimientos se precipitan guiados por el azar y el destino.<\/p>\n<p>Como dec\u00edamos, en esta versi\u00f3n con tintes de comedia,<strong> el autor canario Luis O\u2019malley, muestra a los ni\u00f1os la fuerza po\u00e9tica y ret\u00f3rica de Romeo y Julieta<\/strong> a trav\u00e9s del contraste: el juego de palabras, la convivencia del pasado y el presente, lo cultivado y lo familiar, lo l\u00edrico y los elementos dram\u00e1ticos\u2026\u00a0<\/p>\n<p><strong>Esta compa\u00f1\u00eda de teatro no profesional siempre destina los beneficios que obtiene a ONG\u2019s.<\/strong> En el caso de Romeo y Julieta, los fondos que se recauden con las entradas ir\u00e1n destinados a <strong>proyectos infantiles de M\u00e9dicos Sin Fronteras.<\/strong> Entradas que, est\u00e1n agotadas, <span style=\"font-weight: 400\">excepto para dos pases: el mi\u00e9rcoles por la tarde a las seis y media y el s\u00e1bado por la ma\u00f1ana a las doce y media. Tienen un precio de 14 euros y est\u00e1n a la venta en su p\u00e1gina web <a href=\"https:\/\/unabuenaobra.org\/\">unabuenaobra.org<\/a><\/span><\/p>\n<p>En el \u00faltimo programa charlamos con <strong>su directora, Victoria Farin\u00f3s, y los actores Lucas Casa\u00f1, Gonzalo del Pino, Diana Campillo y Jos\u00e9 Manuel Fern\u00e1ndez.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Entrevista: El elenco de una buena obra\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/1EcWWVfdVLtPJp64ZilSkQ?si=MPxIM-a9SfSCIW2hsVQjLQ&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El \u00faltimo programa de Bruselas con \u00d1 se convirti\u00f3 en un para\u00edso cultural que llev\u00f3 hasta nuestros oyentes desde un festival de m\u00fasica belga y valenciana hasta la cl\u00e1sica joya de teatro que la compa\u00f1\u00eda <a class=\"mh-excerpt-more\" href=\"https:\/\/radioalma.eu\/bruselas\/2024\/10\/14\/una-buena-obra-lleva-al-escenario-una-version-comica-de-romeo-y-julieta\/\" title=\"&#8216;Una Buena Obra&#8217; lleva al escenario una versi\u00f3n c\u00f3mica de Romeo y Julieta\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":51,"featured_media":12451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,2700],"tags":[],"class_list":{"0":"post-12430","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-agenda-cultural","8":"category-cultura"},"_links":{"self":[{"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/posts\/12430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/comments?post=12430"}],"version-history":[{"count":0,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/posts\/12430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/media\/12451"}],"wp:attachment":[{"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/media?parent=12430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/categories?post=12430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/tags?post=12430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}