{"id":2026,"date":"2015-12-08T13:51:32","date_gmt":"2015-12-08T12:51:32","guid":{"rendered":"http:\/\/radioalma.eu\/bruselas\/?p=2026"},"modified":"2015-12-08T13:51:32","modified_gmt":"2015-12-08T12:51:32","slug":"la-cumbre-de-paris-se-enfrenta-al-reto-de-frenar-el-calentamiento-global-del-planeta","status":"publish","type":"post","link":"https:\/\/radioalma.eu\/bruselas\/2015\/12\/08\/la-cumbre-de-paris-se-enfrenta-al-reto-de-frenar-el-calentamiento-global-del-planeta\/","title":{"rendered":"La Cumbre de Par\u00eds se enfrenta al reto de frenar el calentamiento global del planeta"},"content":{"rendered":"<p><a href=\"http:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/197838_a_1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2029\" src=\"http:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/197838_a_1-300x200.jpg\" alt=\"197838_a_1\" width=\"300\" height=\"200\" srcset=\"https:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/197838_a_1-300x200.jpg 300w, https:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/197838_a_1-1024x683.jpg 1024w, https:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/197838_a_1-768x512.jpg 768w, https:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/197838_a_1-1536x1024.jpg 1536w, https:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/197838_a_1-2048x1365.jpg 2048w, https:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/197838_a_1-150x100.jpg 150w, https:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/197838_a_1-900x600.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Par\u00eds est\u00e1 siendo centro de todas las miradas del planeta. En esta ocasi\u00f3n, el motivo ha sido la Cumbre del Clima, en la que se han citado casi todos los dirigentes mundiales con un \u00fanico objetivo: tratar de frenar el Cambio Clim\u00e1tico. Concretamente, se pretende que la temperatura no suba m\u00e1s de dos grados antes de fin de siglo.<\/p>\n<p>En nuestro \u00faltimo Bruselas con \u00d1 hemos contactado con Manuel de Castro, Catedr\u00e1tico de F\u00edsica de la Tierra de la Universidad de Castilla La Mancha, para saber cu\u00e1les ser\u00e1n las consecuencias de ese calentamiento global: el aumento de dos grados provocar\u00e1 el deshielo de los polos, y eso supondr\u00e1 que el nivel del mar suba 7 metros.<\/p>\n<p>De Castro apuesta por seguir llamando la atenci\u00f3n de los gobiernos ya que \u201cla posibilidad de no sobrepasar esos 2 grados de calentamiento del planeta se nos esfuma\u201d.<\/p>\n<p>&nbsp;<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2026-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/planeta-I.mp3?_=1\" \/><a href=\"http:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/planeta-I.mp3\">http:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/planeta-I.mp3<\/a><\/audio>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2026-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/planeta-II.mp3?_=2\" \/><a href=\"http:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/planeta-II.mp3\">http:\/\/radioalma.eu\/bruselas\/files\/2015\/12\/planeta-II.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Par\u00eds est\u00e1 siendo centro de todas las miradas del planeta. En esta ocasi\u00f3n, el motivo ha sido la Cumbre del Clima, en la que se han citado casi todos los dirigentes mundiales con un \u00fanico <a class=\"mh-excerpt-more\" href=\"https:\/\/radioalma.eu\/bruselas\/2015\/12\/08\/la-cumbre-de-paris-se-enfrenta-al-reto-de-frenar-el-calentamiento-global-del-planeta\/\" title=\"La Cumbre de Par\u00eds se enfrenta al reto de frenar el calentamiento global del planeta\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":51,"featured_media":2029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[891,890,889,892,22],"class_list":{"0":"post-2026","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cronica","8":"tag-calentamiento-global","9":"tag-cambio-climatico","10":"tag-cumbre-paris","11":"tag-kioto","12":"tag-tertulia"},"_links":{"self":[{"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/posts\/2026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/comments?post=2026"}],"version-history":[{"count":0,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/posts\/2026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/media\/2029"}],"wp:attachment":[{"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/media?parent=2026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/categories?post=2026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioalma.eu\/bruselas\/wp-json\/wp\/v2\/tags?post=2026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}