{"id":1700,"date":"2019-11-22T14:00:00","date_gmt":"2019-11-22T13:00:00","guid":{"rendered":"http:\/\/radioalma.eu\/lavozdecharo\/?p=1700"},"modified":"2019-12-12T11:44:46","modified_gmt":"2019-12-12T10:44:46","slug":"las-mujeres-maltratadas-se-sienten-culpables","status":"publish","type":"post","link":"https:\/\/radioalma.eu\/lavozdecharo\/2019\/11\/22\/las-mujeres-maltratadas-se-sienten-culpables\/","title":{"rendered":"Mujeres maltratadas: v\u00edctimas que se sienten culpables"},"content":{"rendered":"\n<p>Nos lo cuenta Sonia Vivas, que ha escrito un libro \u00ab\u00a0Vivas nos queremos\u00a0\u00bb en donde cuenta su experiencia como polic\u00eda local, por la que trat\u00f3 a muchas mujeres maltratadas y a sus agresores.  Nos dice que, aunque llegan destrozadas a la comisar\u00eda, a\u00fan se preocupan por la suerte que correr\u00e1 su agresor, el cual, sin embargo, pretende convencer a la polic\u00eda de que la mala es ella.  Tambi\u00e9n cuenta en el libro qu\u00e9 hacer si un individuo te va a agredir. \u00ab\u00a0Vivas nos queremos\u00a0\u00bb, de Sonia Vivas, editorial Montena<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"http:\/\/radioalma.eu\/lavozdecharo\/files\/2019\/12\/Entrevista-a-Sonia-Vivas-vivas-las-queremos-2019-11-22.mp3\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Nos lo cuenta Sonia Vivas, que ha escrito un libro \u00ab\u00a0Vivas nos queremos\u00a0\u00bb en donde cuenta su experiencia como polic\u00eda local, por la que trat\u00f3 a muchas mujeres maltratadas y a sus agresores. Nos dice <a class=\"mh-excerpt-more\" href=\"https:\/\/radioalma.eu\/lavozdecharo\/2019\/11\/22\/las-mujeres-maltratadas-se-sienten-culpables\/\" title=\"Mujeres maltratadas: v\u00edctimas que se sienten culpables\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-1700","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-non-classe"},"_links":{"self":[{"href":"https:\/\/radioalma.eu\/lavozdecharo\/wp-json\/wp\/v2\/posts\/1700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioalma.eu\/lavozdecharo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioalma.eu\/lavozdecharo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioalma.eu\/lavozdecharo\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/radioalma.eu\/lavozdecharo\/wp-json\/wp\/v2\/comments?post=1700"}],"version-history":[{"count":0,"href":"https:\/\/radioalma.eu\/lavozdecharo\/wp-json\/wp\/v2\/posts\/1700\/revisions"}],"wp:attachment":[{"href":"https:\/\/radioalma.eu\/lavozdecharo\/wp-json\/wp\/v2\/media?parent=1700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioalma.eu\/lavozdecharo\/wp-json\/wp\/v2\/categories?post=1700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioalma.eu\/lavozdecharo\/wp-json\/wp\/v2\/tags?post=1700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}